{"id":4273,"date":"2024-12-04T12:32:02","date_gmt":"2024-12-04T11:32:02","guid":{"rendered":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg"},"modified":"2024-12-04T12:32:02","modified_gmt":"2024-12-04T11:32:02","slug":"festa-del-gorgonzola-extra-large-2","status":"inherit","type":"attachment","link":"https:\/\/www.caseificioangelocroce.it\/en\/festa-del-gorgonzola-extra-large-2\/","title":{"rendered":"Festa-del-Gorgonzola-extra-large"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-4273","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festa-del-Gorgonzola-extra-large - Caseificio Angelo Croce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festa-del-Gorgonzola-extra-large - Caseificio Angelo Croce\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Caseificio Angelo Croce\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caseificioangelocroce\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.caseificioangelocroce.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Festa-del-Gorgonzola-extra-large.jpg\",\"url\":\"https:\\\/\\\/www.caseificioangelocroce.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Festa-del-Gorgonzola-extra-large.jpg\",\"name\":\"Festa-del-Gorgonzola-extra-large - Caseificio Angelo Croce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.caseificioangelocroce.it\\\/#website\"},\"datePublished\":\"2024-12-04T11:32:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.caseificioangelocroce.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Festa-del-Gorgonzola-extra-large.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.caseificioangelocroce.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Festa-del-Gorgonzola-extra-large.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.caseificioangelocroce.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Festa-del-Gorgonzola-extra-large.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.caseificioangelocroce.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festa-del-Gorgonzola-extra-large\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.caseificioangelocroce.it\\\/#website\",\"url\":\"https:\\\/\\\/www.caseificioangelocroce.it\\\/\",\"name\":\"Caseificio Angelo Croce\",\"description\":\"Capolavori, dal 1880\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.caseificioangelocroce.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festa-del-Gorgonzola-extra-large - Caseificio Angelo Croce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg","og_locale":"en_US","og_type":"article","og_title":"Festa-del-Gorgonzola-extra-large - Caseificio Angelo Croce","og_url":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg","og_site_name":"Caseificio Angelo Croce","article_publisher":"https:\/\/www.facebook.com\/caseificioangelocroce","og_image":[{"width":800,"height":549,"url":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg","url":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg","name":"Festa-del-Gorgonzola-extra-large - Caseificio Angelo Croce","isPartOf":{"@id":"https:\/\/www.caseificioangelocroce.it\/#website"},"datePublished":"2024-12-04T11:32:02+00:00","breadcrumb":{"@id":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caseificioangelocroce.it\/en\/"},{"@type":"ListItem","position":2,"name":"Festa-del-Gorgonzola-extra-large"}]},{"@type":"WebSite","@id":"https:\/\/www.caseificioangelocroce.it\/#website","url":"https:\/\/www.caseificioangelocroce.it\/","name":"Caseificio Angelo Croce","description":"Capolavori, dal 1880","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caseificioangelocroce.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"206\" src=\"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large-300x206.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large-300x206.jpg 300w, https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large-768x527.jpg 768w, https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":549,"file":"2022\/09\/Festa-del-Gorgonzola-extra-large.jpg","filesize":33770,"sizes":{"medium":{"file":"Festa-del-Gorgonzola-extra-large-300x206.jpg","width":300,"height":206,"filesize":10194,"mime_type":"image\/jpeg","source_url":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large-300x206.jpg"},"thumbnail":{"file":"Festa-del-Gorgonzola-extra-large-150x150.jpg","width":150,"height":150,"filesize":7225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large-150x150.jpg"},"medium_large":{"file":"Festa-del-Gorgonzola-extra-large-768x527.jpg","width":768,"height":527,"filesize":27672,"mime_type":"image\/jpeg","source_url":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large-768x527.jpg"},"full":{"file":"Festa-del-Gorgonzola-extra-large.jpg","width":800,"height":549,"mime_type":"image\/jpeg","source_url":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/www.caseificioangelocroce.it\/wp-content\/uploads\/2022\/09\/Festa-del-Gorgonzola-extra-large.jpg","filename":"Festa-del-Gorgonzola-extra-large.jpg","filesize":33770,"_links":{"self":[{"href":"https:\/\/www.caseificioangelocroce.it\/en\/wp-json\/wp\/v2\/media\/4273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caseificioangelocroce.it\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.caseificioangelocroce.it\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.caseificioangelocroce.it\/en\/wp-json\/wp\/v2\/users\/1"}]}}